{"id":4212,"date":"2009-04-07T12:16:06","date_gmt":"2009-04-07T19:16:06","guid":{"rendered":"https:\/\/elenemigocomun.net\/?p=4212"},"modified":"2016-10-20T21:29:35","modified_gmt":"2016-10-21T04:29:35","slug":"retrasan-sentencia-david-venegas-reyes","status":"publish","type":"post","link":"https:\/\/elenemigocomun.net\/es\/2009\/04\/retrasan-sentencia-david-venegas-reyes\/","title":{"rendered":"Retrasan Sentencia de David Venegas Reyes"},"content":{"rendered":"<p>SEGUIMIENTO DE ACCION URGENTE: <strong>RETRASAN SENTENCIA DE DAVID VENEGAS REYES \u201cALEBRIJE\u201d PARA EL DIA 13 DE ABRIL DE 2009 CUANDO SE CUMPLEN DOS A\u00d1OS DE SU DETENCION.<\/strong><\/p>\n<p><strong>Hechos:<\/strong> El d\u00eda 6 de abril de este a\u00f1o 2009 a las diez con cuarenta y cinco minutos de la ma\u00f1ana* el compa\u00f1ero David Venegas se hizo presente en el juzgado tercero de distrito, a cargo del lic. Amado Chi\u00f1as Fuentes para conocer la decisi\u00f3n de sentencia en torno al delito fabricado por el mal gobierno que se refiere a <strong>POSESI\u00d3N CON HIP\u00d3TESIS DE VENTA DE COCA\u00cdNA Y HERO\u00cdNA<\/strong> por el cual el compa\u00f1ero fue hecho preso el trece de abril de 2007 y uno de los dos procesos penales por los cuales paso once meses en prisi\u00f3n, el otro delito por el cual estuvo preso <strong>y se ha logrado demostrar totalmente su inocencia<\/strong> es el de SEDICI\u00d3N, ASOCIACI\u00d3N DELICTUOSA Y DA\u00d1OS POR INCENDIO en contra de ocho edificios del centro hist\u00f3rico por los hechos del 25 de noviembre de 2006. <\/p>\n<p>Mientras tanto afuera del juzgado un grupo de compa\u00f1eros y compa\u00f1eras de la Asamblea Popular de los pueblos de Oaxaca se hicieron presentes en solidaridad y en demostraci\u00f3n de fuerza, mientras aguardaban esta resoluci\u00f3n.<\/p>\n<p><!--more--><\/p>\n<p>Sin embargo y como es com\u00fan en los procesos judiciales que se siguen en contra de  compa\u00f1eros participantes en el movimiento social, el juzgado determina, argumentando cuestiones administrativas nimias, que no se pod\u00eda llevar a cabo la audiencia y <strong>decidi\u00f3 posponerla, de nada valieron las argumentaciones y haber llegado en tiempo y forma, la decisi\u00f3n de dilatar el proceso y retardar la sentencia estaba tomada<\/strong>. Sin embargo exigimos conocer en ese mismo momento una nueva fecha de cuando se llevara cabo la audiencia final y la sentencia. La cual quedo acordada el <strong>trece de abril de este a\u00f1o 2009 a las diez con cuarenta y cinco de la ma\u00f1ana<\/strong>. Es de resaltar que es precisamente <strong>el trece de abril cuando el compa\u00f1ero David Venegas fue detenido hace dos a\u00f1os.<\/strong><\/p>\n<p>Observamos una clara intenci\u00f3n de retrasar el proceso con el \u00fanico fin de seguir teniendo al compa\u00f1ero David Venegas sometido a proceso y de esta manera seguir maniatando su participaci\u00f3n plena en el movimiento social, no es este el \u00fanico caso, la dilaci\u00f3n en las sentencias y al final las sentencias adversas ha sido una practica com\u00fan de los jueces de consigna en los casos de los compa\u00f1eros y compa\u00f1eras que forman parte del movimiento social. Adem\u00e1s que este retraso tambi\u00e9n puede deberse a que el gobierno esta buscando medir la respuesta del movimiento social en un momento dado en el caso de una sentencia condenatoria, Es por ello con mas fuerza seguimos convocando:<\/p>\n<p><strong>A LA SOLIDARIDAD DE TODOS LOS HOMBRES Y MUJERES, ORGANIZACIONES, COLECTIVOS, PUEBLOS Y SINDICATOS, DE OAXACA, M\u00c9XICO Y EL MUNDO PARA QUE SE MANIFIESTEN POR MEDIO DE CARTAS, LLAMADAS TELEFONICAS, FAXES U OTRAS ACCIONES DE PROTESTA, DIRIGIDAS AL JUEZ AMADO CHI\u00d1AS FUENTES, JUEZ TERCERO DE DISTRITO DEL D\u00c9CIMO TERCER CIRCUITO CON DOMICILIO EN AVENIDA JU\u00c1REZ 709, COLONIA CENTRO, C\u00d3DIGO POSTAL 68000, TELEFONO DE ESTA CIUDAD DE OAXACA DE JU\u00c1REZ, OAXACA, PARA EXIGIR QUE DAVID SEA SENTENCIADO LIBRE TOTALMENTE. ESTAS ACCIONES PROPONEMOS QUE SE HAGAN ANTES DE LA SENTENCIA FINAL QUE SERA EL DIA 6 DE ABRIL DE 2009 A LAS 10:45 DE LA MA\u00d1ANA EN EL JUZGADO TERCERO DE DISTRITO FEDERAL DE ESTA CIUDAD.<\/strong><\/p>\n<p>ASI MISMO SEGUIMOS EXIGIENDO LA SALIDA DEL ASESINO ULISES RUIZ ORTIZ DEL GOBIENRO DE OAXACA, COMO LO SEGUIREMOS HACIENDO HASTA EL ULTIMO DIA DE SU NEFASTO GOBIERNO Y NO DESCANSAREMOS EN LUCHAR PARA LOGRAR UN CAMBIO PROFUNDO Y RADICAL DE NUESTRA SOCIEDAD, ASI MISMO NOS SOLIDARIZAMOS CON LOS PUEBLOS QUE EN TODO EL MUNDO TAMBIEN LUCHAN POR UN MUNDO MEJOR.<\/p>\n<p><center><strong>\u00a1FUERA ULISES RUIZ POR ASESINO!<br \/>\n\u00a1LIBERTAD A TODOS LIOS PRESOS POLITCOS DE OAXACA, MEXICO Y EL MUNDO!<br \/>\n\u00a1CASTIGO A TODOS LOS RESPONSABLES DE LA REPRESION CONTRA LOS PUEBLOS DE OAXACA!<br \/>\n\u00a1LA APPO VIVE, LA LUCHA SIGUE!<\/p>\n<p>FRATERNALMENTE<br \/>\nVOCES OAXAQUE\u00d1AS CONSTRUYENDO AUTONOMIA Y LIBERTAD<\/p>\n<p>Para  firmar este comunicado enviarlo firmado al correo de vocal (<a href=\"mailto:vocal@riseup.net\">vocal@riseup.net<\/a>)<\/p>\n<p>Para enviar cartas, al Juez Amado Chi\u00f1as Fuentes enviarlas al Juzgado Tercero de Distrito del D\u00e9cimo Tercer Circuito, con domicilio en Avenida Ju\u00e1rez 709, Colonia Centro, Oaxaca de Ju\u00e1rez, Oaxaca, CP 68000.<br \/>\nPara hacer llamadas o enviar faxes, favor de llamar al 01 (951) 5156600 y pedir el numero de fax.<\/strong><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SEGUIMIENTO DE ACCION URGENTE: RETRASAN SENTENCIA DE DAVID VENEGAS REYES \u201cALEBRIJE\u201d PARA EL DIA 13 DE ABRIL DE 2009 CUANDO SE CUMPLEN DOS A\u00d1OS DE SU DETENCION. Hechos: El d\u00eda 6 de abril de este a\u00f1o 2009 a las diez con cuarenta y cinco minutos de la ma\u00f1ana* el compa\u00f1ero David Venegas se hizo presente [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":14908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":1,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[163,164],"tags":[],"class_list":["post-4212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presos","category-solidaridad"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2009\/04\/david-venegas.jpg","_links":{"self":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts\/4212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/comments?post=4212"}],"version-history":[{"count":0,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts\/4212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/media\/14908"}],"wp:attachment":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/media?parent=4212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/categories?post=4212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/tags?post=4212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}