{"id":8431,"date":"2008-01-04T19:56:22","date_gmt":"2008-01-05T02:56:22","guid":{"rendered":"https:\/\/elenemigocomun.net\/?p=8431"},"modified":"2016-10-24T10:56:22","modified_gmt":"2016-10-24T17:56:22","slug":"la-lucha-sigue","status":"publish","type":"post","link":"https:\/\/elenemigocomun.net\/es\/2008\/01\/la-lucha-sigue\/","title":{"rendered":"La Lucha Sigue"},"content":{"rendered":"<p><strong>x <em>David Venegas Reyes \u00abAlebrije\u00bb<\/em><\/strong><\/p>\n<p>Termin\u00f3 el a\u00f1o de 2007 en Oaxaca, un largo y doloroso a\u00f1o de injusticia, represi\u00f3n, desapariciones forzadas, elecciones de estado y muerte, pero tambi\u00e9n un a\u00f1o de resistencia digna y heroica de muchos hombres y mujeres. Mientras los poderosos y los pol\u00edticos que se benefician del estado de cosas actual, se regodean en el discurso de la vuelta a la paz y la tranquilidad en Oaxaca y de una reconciliaci\u00f3n entre sus habitantes, por debajo de ese discurso, en sus acciones desconfiadas, cautelosas y temerosas y sobre todo represivas y violentas dan a notar su verdadera percepci\u00f3n, que en Oaxaca existe una polarizaci\u00f3n social y una agudizaci\u00f3n de las contradicciones sociales mas cruda y grave que nunca. Mientras sus discursos hablan de paz sus armas, escudos y toletes ladran guerra.<\/p>\n<p><!--more--><\/p>\n<p>En 2006 el gobierno mexicano le neg\u00f3 la posibilidad a los pueblos de Oaxaca de un victoria superficial, que no afectaba el sistema de explotaci\u00f3n miseria y muerte que nos malgobierna. La salida de Ulises Ruiz del gobierno de Oaxaca no afectaba las bases econ\u00f3micas, pol\u00edticas e ideol\u00f3gicas en que se sostiene este estado de cosas. Con convocar a nuevas elecciones, la clase pol\u00edtica que gobierna el pa\u00eds hubiera salvado la creencia en la legitimidad de su democracia oligarca y orden constitucional. Al hacer esto, algunos de los y las l\u00edderes del consejo de la APPO, pol\u00edticos tradicionales, hubieran gustosamente levantado la mano para insertarse en el sistema y el movimiento de los pueblos de Oaxaca habr\u00eda devenido seguramente, como aspira el compa\u00f1ero preso pol\u00edtico Flavio Sosa, en un movimiento humanista y democr\u00e1tico, eufemismos de electorero y perredista.<\/p>\n<p>Al negarse a conceder la demanda de la salida de Ulises Ruiz y en su lugar reprimir salvajemente a nuestros pueblos, el sistema se desnudo completo y mostr\u00f3 la fuente de donde emana su injusticia, violencia y discriminaci\u00f3n. Al correrse el tel\u00f3n de la farsa electoral democr\u00e1tica que se representa absurdamente en nuestro pa\u00eds se develaron tras de el como enormes columnas que sostienen la cabeza de Ulises Ruiz, el sistema de producci\u00f3n capitalista, la falsa democracia representativa y la ideolog\u00eda occidental de los poderosos. De esta manera y como tantas veces en la historia, son los mismos poderosos, quienes con su represi\u00f3n, necedad y crimen han provocado que las aspiraciones de los hombres y mujeres de Oaxaca levantados se eleven mas alla de la sola renuncia del tirano represor Ulises Ruiz.<\/p>\n<p>El curso y las caracter\u00edsticas de esta lucha ya han rebasado los canales que propone el sistema de gobierno que nos oprime. El descontento se ha dispersado en muchos caminos diferentes, principalmente por el proceso de toma de conciencia de sus participantes, pero tambi\u00e9n por la desesperaci\u00f3n que provoca la lentitud de los cambios y las limitaciones que muestran los \u00f3rganos de lucha principales en la primera etapa del movimiento, esto lo demuestra la nula confianza que obtuvieron la clase pol\u00edtica de todos los partidos, de derecha y de supuesta izquierda en las elecciones del a\u00f1o pasado, cuando los hombres y mujeres de Oaxaca les propinaron una gran lecci\u00f3n con el abstencionismo mas grande que se ha visto en Oaxaca y el pa\u00eds en muchos a\u00f1os, el cual fue un rotundo \u00a1no les creemos mas! A todos esos y esas pol\u00edticos tradicionales que viven de la esperanza de la gente sencilla de abajo. En el \u00e1mbito de la lucha pacifica de los pueblos de Oaxaca, ahora ya no es solo considerada la v\u00eda institucional y falsamente democr\u00e1tica que propone la clase pol\u00edtica y tampoco es suficiente con la salida de Ulises Ruiz.<\/p>\n<p>En este entorno, la lucha por la autonom\u00eda que desde hace mas de 500 a\u00f1os llevan acabo los pueblos indios de M\u00e9xico y que cada vez mas es comprendida y reconocida por los habitante de la ciudades como una alternativa real para mejorar sus vidas, cobra un papel protag\u00f3nico en la lucha de nuestros pueblos de Oaxaca. Lejos de los afanes autoritarios y hegem\u00f3nicos de algunas propuestas de izquierda y lejos tambi\u00e9n de la mediocridad del camino electoral, plagado de trampas y recovecos in\u00fatiles, ambas propuestas aparentemente distantes pero que en la practica muchas veces se funden y toman formas quim\u00e9ricas irreconocibles te\u00f3ricamente, aunque bastante reconocidas en la practica pol\u00edtica tradicional, bajo el nombre de oportunismo pol\u00edtico, la lucha por la autonom\u00eda conjunta los elementos de dignidad, honestidad, radicalidad y sabidur\u00eda que la han hecho ser la bandera de los movimientos sociales mas dignos y honestos ademas de poderosos en la ultima d\u00e9cada entre los pa\u00edses latinoamericanos, desde el levantamiento zapatista en Chiapas en 1994 hasta el movimiento quechua y aymara de Bolivia, se ondean en lo alto la bandera de la autonom\u00eda.<\/p>\n<p>En Oaxaca, un estado donde en sus regiones habitan diez y seis naciones indias, dispersas en diez mil comunidades y donde los y las que vivimos en las ciudades somos descendientes y herederos de esa civilizaci\u00f3n mesoamericana, la autonom\u00eda es una realidad en muchos pueblos en la forma del r\u00e9gimen de autogobierno de los usos y costumbres y aunque acotada y agredida por el gobierno y los partidos pol\u00edticos, la practica auton\u00f3mica que es posible observar en muchas comunidades indias y mestizas, es ejemplo para prever su viabilidad en toda nuestra sociedad.<\/p>\n<p>Mientras tanto miles de hombres y mujeres por todo el estado siguen participando activamente pero sobre todo honestamente en el movimiento social, son como aquellos indispensables que habla el che Guevara y que mantienen amorosa y abnegadamente la llama de la rebeld\u00eda emancipatoria viva, por todos aquellos y aquellas que en este momento atemorizados, decepcionados y desesperanzados, tratan de volverla mirada de la injusticia cotidiana a los miles de placeres inmediatos que ofrece el sistema para mantener ocupados y sometidos a los pueblos. Las telenovelas han recuperado paulatinamente su audiencia, el futbol a sus porras y la catedral sus misas de domingo llenas, mientras los aurreras y dem\u00e1s tiendas extranjeras recuperan sus largas colas en las cajas registradoras en la febril e intensa actividad navide\u00f1a, de fin de a\u00f1o y reyes magos de gastar, consumir, necesitar y enriquecer las bolsas de los poderosos. Es verdad, todo parece como antes, o casi todo, pero las apariencias enga\u00f1an, pues la experiencia \u00fanica y maravillosa de libertad que vivimos los y las oaxaque\u00f1os hace ya mas de un a\u00f1o en el momento de mayor combatividad del movimiento es imborrable. Mas de una generaci\u00f3n han quedado marcadas con esta experiencia y las consecuencias de esta toma de conciencia de los oaxaque\u00f1os y las oaxaque\u00f1as apenas empiezan a observarse. El trabajo de los y las indispensables parte de la premisa magnifica de un pueblo que es consciente de su dura e injusta realidad pero sobre todo de su fortaleza inmensa cuando se decide a actuar.<\/p>\n<p>Este 2008 se inaugura con una nueva oleada de reformas y agresiones a la vida de los trabajadores y campesinos de todo M\u00e9xico, la liberaci\u00f3n total a las importaciones de ma\u00edz, frijol, leche y az\u00facar de Estados Unidos, el incremento al precio de la gasolina y del transporte publico, la aprobaci\u00f3n de la reforma judicial que legaliza la represi\u00f3n de toda inconformidad y protesta social, el peligro del reinicio de la guerra en Chiapas por nuevas agresiones del ejercito y grupos paramilitares a las comunidades zapatistas y el despojo de las tierras recuperadas en el levantamiento de 1994, la necedad del gobierno mexicano de construir la presa de la parota en Guerrero en contra de la voluntad de los 42 pueblos afectados, son solo algunos ejemplos del inicio de esta nueva andanada de agresiones de los poderosos al derecho de vivir dignamente de los hombres y mujeres de nuestro pa\u00eds. Pero a pesar del clima permanente de amenazas de represi\u00f3n y violencia por parte del gobierno de Felipe Calder\u00f3n, el M\u00e9xico de abajo, trabajador y paciente pero tambi\u00e9n valiente, rebelde y bronco habr\u00e1 de despertar del letargo en que lo tienen sumido las promesas nunca satisfechas de una democracia que funciona, unos partidos pol\u00edticos que representan al pueblo y un desarrollo que produzca bienestar para todos y todas y este M\u00e9xico de abajo, habr\u00e1 de ofrecer las batallas necesarias para erradicar a injusticia, explotaci\u00f3n y miseria que nos oprimen.<\/p>\n<p>Al iniciar este a\u00f1o 2008, es de fundamental importancia el mirarnos, reconocernos y reencontrarnos en la lucha que emprendimos los y las oaxaque\u00f1as y oaxaque\u00f1os hace ya mas de un a\u00f1o. Mientras Ulises Ruiz siga como gobernador, mientras los causantes de nuestro sufrimiento sigan presentes ah\u00ed tan c\u00ednica e impunemente y profundizando su corrupci\u00f3n, violencia y mentiras, mientras las bases econ\u00f3mica, pol\u00edtica e ideol\u00f3gica en que se sostiene este sistema de explotaci\u00f3n miseria y muerte que nos malgobierna sigan ordenando nuestras vidas, mientras nuestros 24 asesinados y asesinadas no obtengan justicia, nuestros desaparecidos no sean presentados con vida y los presos y presas pol\u00edticos de todo el estado, de San Agust\u00edn Loxicha, de San Blas Atempa, de Santiago Xanica, de Guevea de Humboldt, de San Isidro Aloapan, de la APPO, no obtengamos libertad inmediata e incondicional y sean castigados los responsables del sufrimiento de nuestra gente, solo entonces podremos decir que en Oaxaca hay paz verdadera con justicia y dignidad. Hasta entonces, es responsabilidad moral de todos y todas quienes sientan en su coraz\u00f3n la flama de la rebeld\u00eda y el amor por la justicia, la dignidad y la paz el seguir luchando de manera digna, valiente, y combativa. En momentos de debilidad o desesperanza recordemos que somos muchos y muchas, que somos la inmensa mayor\u00eda, que ya una vez, hace no mucho tiempo nos vimos a la cara y nos reconocimos iguales en nuestro sufrimiento pero tambi\u00e9n en nuestra rebeld\u00eda e hicimos posible la fiesta mas grande de libertad que ha ocurrido en nuestro pa\u00eds en los \u00faltimos a\u00f1os, en la comuna de Oaxaca. Con su necedad, ceguera y autoritarismo, los poderosos est\u00e1n abonando a una nueva y mas poderosa insurrecci\u00f3n, la cual seguramente habr\u00e1 de ser definitiva.<\/p>\n<p>Arrancaron nuestros frutos, trozaron nuestras ramas, quemaron nuestros troncos pero no pudieron arrancar nuestras ra\u00edces.<\/p>\n<p>David Venegas Reyes \u00abAlebrije\u00bb<br \/>\nPenitenciaria Central de Santa Maria Ixcotel.<br \/>\n4 de Enero de 2008.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>x David Venegas Reyes \u00abAlebrije\u00bb Termin\u00f3 el a\u00f1o de 2007 en Oaxaca, un largo y doloroso a\u00f1o de injusticia, represi\u00f3n, desapariciones forzadas, elecciones de estado y muerte, pero tambi\u00e9n un a\u00f1o de resistencia digna y heroica de muchos hombres y mujeres. Mientras los poderosos y los pol\u00edticos que se benefician del estado de cosas actual, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":15303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":1,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[163],"tags":[397],"class_list":["post-8431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presos","tag-santa-maria-ixcotel-es"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2008\/02\/pp_david_venegas.jpg","_links":{"self":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts\/8431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/comments?post=8431"}],"version-history":[{"count":0,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts\/8431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/media\/15303"}],"wp:attachment":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/media?parent=8431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/categories?post=8431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/tags?post=8431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}