{"id":9674,"date":"2012-01-27T16:59:33","date_gmt":"2012-01-27T23:59:33","guid":{"rendered":"https:\/\/elenemigocomun.net\/?p=9674"},"modified":"2016-10-12T21:55:04","modified_gmt":"2016-10-13T04:55:04","slug":"policia-detiene-caravana-desplazados","status":"publish","type":"post","link":"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/","title":{"rendered":"Polic\u00eda detiene caravana de desplazados de San Juan Copala"},"content":{"rendered":"<p>Aproximadamente 200 polic\u00edas, adscritos a la Secretar\u00eda de Seguridad P\u00fablica de Oaxaca, impiden el paso de la caravana de desplazados triquis que pretenden regresar a la cabecera cultural y ceremonial de San Juan Copala. Los efectivos policiacos se han apostado en el kil\u00f3metro 7, del municipio de Tlaxiaco, para impedir que los ni\u00f1os, mujeres y hombres lleguen a la regi\u00f3n triqui.<\/p>\n<p>En el grupo viajan 71 mujeres, 24 ni\u00f1os y 26 hombres triquis. Adem\u00e1s, 47 integrantes de Organizaciones No Gubernamentales, observadores internacionales, defensores de derechos humanos e integrantes de un medio de comunicaci\u00f3n alternativo.<\/p>\n<p>Integrantes de la caravana aseguran que fue dinamitado un tramo de la carretera, a la altura de la poblaci\u00f3n de Santa Catarina, para impedir el paso.<\/p>\n<p><!--more--><\/p>\n<p>Dicen que el operativo policiaco es encabezado por V\u00edctor Ra\u00fal Mart\u00ednez, coordinador de asesores del gobernador Gabino Cu\u00e9 Monteagudo.<\/p>\n<p>Los hechos se dan a 24 horas de que el grupo de desplazados firmara un acuerdo de paz, en presencia del gobernador oaxaque\u00f1o. Sin embargo, en reuniones sostenidas hasta la ma\u00f1ana del jueves, integrantes de la Unidad de Bienestar Social de la Regi\u00f3n Triqui (UBISORT) y del Movimiento de Unificaci\u00f3n y Lucha Triqui (MULT) mostraron su desacuerdo en que los desplazados regresaran a Copala en esta semana. Ante la imposibilidad de llegar a un acuerdo, el gobernador Gabino Cu\u00e9 habr\u00eda dicho que no se compromet\u00eda a garantizar la seguridad de los desplazados.<\/p>\n<p>\u2013<\/p>\n<p>Fotos por Editorial Huasipungo Tierra Roja<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1290\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/elenemigocomun.net\\\/es\\\/2012\\\/01\\\/policia-detiene-caravana-desplazados\\\/&quot;,&quot;likes_blog_id&quot;:1095693}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1290px; height: 646px;\" data-original-width=\"1290\" data-original-height=\"646\" > <div class=\"gallery-group images-1\" style=\"width: 860px; height: 646px;\" data-original-width=\"860\" data-original-height=\"646\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_1\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"856\"> <meta itemprop=\"height\" content=\"642\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14099\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_1\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1.jpg?w=856&#038;h=642&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_1-640x480.jpg 640w\" width=\"856\" height=\"642\" loading=\"lazy\" data-original-width=\"856\" data-original-height=\"642\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_1\" alt=\"policia-detiene-caravana_1\" style=\"width: 856px; height: 642px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 430px; height: 646px;\" data-original-width=\"430\" data-original-height=\"646\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"426\"> <meta itemprop=\"height\" content=\"319\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14100\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_2\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2.jpg?w=426&#038;h=319&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_2-640x480.jpg 640w\" width=\"426\" height=\"319\" loading=\"lazy\" data-original-width=\"426\" data-original-height=\"319\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_2\" alt=\"policia-detiene-caravana_2\" style=\"width: 426px; height: 319px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_3\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"426\"> <meta itemprop=\"height\" content=\"319\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14101\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_3\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3.jpg?w=426&#038;h=319&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_3-640x480.jpg 640w\" width=\"426\" height=\"319\" loading=\"lazy\" data-original-width=\"426\" data-original-height=\"319\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_3\" alt=\"policia-detiene-caravana_3\" style=\"width: 426px; height: 319px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1290px; height: 324px;\" data-original-width=\"1290\" data-original-height=\"324\" > <div class=\"gallery-group images-1\" style=\"width: 430px; height: 324px;\" data-original-width=\"430\" data-original-height=\"324\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_4\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"426\"> <meta itemprop=\"height\" content=\"320\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14102\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_4\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4.jpg?w=426&#038;h=320&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_4-640x480.jpg 640w\" width=\"426\" height=\"320\" loading=\"lazy\" data-original-width=\"426\" data-original-height=\"320\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_4\" alt=\"policia-detiene-caravana_4\" style=\"width: 426px; height: 320px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 430px; height: 324px;\" data-original-width=\"430\" data-original-height=\"324\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_5\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"426\"> <meta itemprop=\"height\" content=\"320\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14103\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_5\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5.jpg?w=426&#038;h=320&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_5-640x480.jpg 640w\" width=\"426\" height=\"320\" loading=\"lazy\" data-original-width=\"426\" data-original-height=\"320\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_5\" alt=\"policia-detiene-caravana_5\" style=\"width: 426px; height: 320px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 430px; height: 324px;\" data-original-width=\"430\" data-original-height=\"324\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_6\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"426\"> <meta itemprop=\"height\" content=\"320\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14104\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_6\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6.jpg?w=426&#038;h=320&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_6-640x480.jpg 640w\" width=\"426\" height=\"320\" loading=\"lazy\" data-original-width=\"426\" data-original-height=\"320\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_6\" alt=\"policia-detiene-caravana_6\" style=\"width: 426px; height: 320px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1290px; height: 243px;\" data-original-width=\"1290\" data-original-height=\"243\" > <div class=\"gallery-group images-1\" style=\"width: 323px; height: 243px;\" data-original-width=\"323\" data-original-height=\"243\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_7\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"319\"> <meta itemprop=\"height\" content=\"239\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14105\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_7\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7.jpg?w=319&#038;h=239&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_7-640x480.jpg 640w\" width=\"319\" height=\"239\" loading=\"lazy\" data-original-width=\"319\" data-original-height=\"239\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_7\" alt=\"policia-detiene-caravana_7\" style=\"width: 319px; height: 239px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 323px; height: 243px;\" data-original-width=\"323\" data-original-height=\"243\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_8\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"319\"> <meta itemprop=\"height\" content=\"239\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14106\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_8\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8.jpg?w=319&#038;h=239&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_8-640x480.jpg 640w\" width=\"319\" height=\"239\" loading=\"lazy\" data-original-width=\"319\" data-original-height=\"239\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_8\" alt=\"policia-detiene-caravana_8\" style=\"width: 319px; height: 239px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 322px; height: 243px;\" data-original-width=\"322\" data-original-height=\"243\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_9\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"318\"> <meta itemprop=\"height\" content=\"239\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14107\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_9\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9.jpg?w=318&#038;h=239&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_9-640x480.jpg 640w\" width=\"318\" height=\"239\" loading=\"lazy\" data-original-width=\"318\" data-original-height=\"239\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_9\" alt=\"policia-detiene-caravana_9\" style=\"width: 318px; height: 239px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 322px; height: 243px;\" data-original-width=\"322\" data-original-height=\"243\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/elenemigocomun.net\/es\/2012\/01\/policia-detiene-caravana-desplazados\/policia-detiene-caravana_10\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"318\"> <meta itemprop=\"height\" content=\"239\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"14108\" data-orig-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"policia-detiene-caravana_10\" data-image-description=\"\" data-medium-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10-300x225.jpg\" data-large-file=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10-640x480.jpg\" src=\"https:\/\/i0.wp.com\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10.jpg?w=318&#038;h=239&#038;ssl=1\" srcset=\"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10.jpg 960w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10-200x150.jpg 200w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10-300x225.jpg 300w, https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana_10-640x480.jpg 640w\" width=\"318\" height=\"239\" loading=\"lazy\" data-original-width=\"318\" data-original-height=\"239\" itemprop=\"http:\/\/schema.org\/image\" title=\"policia-detiene-caravana_10\" alt=\"policia-detiene-caravana_10\" style=\"width: 318px; height: 239px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aproximadamente 200 polic\u00edas, adscritos a la Secretar\u00eda de Seguridad P\u00fablica de Oaxaca, impiden el paso de la caravana de desplazados triquis que pretenden regresar a la cabecera cultural y ceremonial de San Juan Copala. Los efectivos policiacos se han apostado en el kil\u00f3metro 7, del municipio de Tlaxiaco, para impedir que los ni\u00f1os, mujeres y [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":14098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"iawp_total_views":9,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[335],"tags":[],"class_list":["post-9674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-represion"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/elenemigocomun.net\/wp-content\/uploads\/2012\/01\/policia-detiene-caravana.jpg","_links":{"self":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts\/9674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/comments?post=9674"}],"version-history":[{"count":0,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/posts\/9674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/media\/14098"}],"wp:attachment":[{"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/media?parent=9674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/categories?post=9674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elenemigocomun.net\/es\/wp-json\/wp\/v2\/tags?post=9674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}